{"id":3103,"date":"2024-04-27T12:53:31","date_gmt":"2024-04-27T12:53:31","guid":{"rendered":"https:\/\/girbaulab.com\/david-allo-texfor\/"},"modified":"2025-03-18T10:34:50","modified_gmt":"2025-03-18T10:34:50","slug":"david-allo-texfor","status":"publish","type":"post","link":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/","title":{"rendered":"\u00abNuestra industria es l\u00edder en sostenibilidad, pero como ciudadanos tenemos muy poca cultura textil\u00bb"},"content":{"rendered":"<p><a href=\"https:\/\/www.texfor.es\/\" target=\"_blank\" rel=\"noopener\">Texfor<\/a> es la Confederaci\u00f3n de la Industria Textil, la entidad espa\u00f1ola con mayor representatividad del sector textil. Actualmente agrupa a m\u00e1s de 4.000 empresas, la gran mayor\u00eda pymes, que dan empleo a m\u00e1s de 45.000 trabajadores y generan una riqueza anual superior a los 5.000 M\u20ac. Una organizaci\u00f3n clave para acelerar la circularidad de la industria textil. Sobre ello hemos hablado con su responsable de sostenibilidad, David Allo.<\/p>\n<p><strong>\u2013 David, \u00bfest\u00e1 la industria textil espa\u00f1ola preparada para la circularidad?<\/strong><\/p>\n<p>Totalmente. De hecho, somos l\u00edderes internacionales en sostenibilidad. Y es que la industria textil espa\u00f1ola se ha caracterizado por una gran eficiencia de recursos (agua, mermas, qu\u00edmicos, energ\u00eda, residuos, etc), lo que nos ha convertido casi sin quererlo en abanderados del tema. Adem\u00e1s, la legislaci\u00f3n europea es la m\u00e1s exigente en estas cuestiones, por lo que no solo cumplimos, si no que contamos con certificados que nos avalan.<\/p>\n<p>El gran problema de toda esta transici\u00f3n legislativa es la coherencia de la legislaci\u00f3n. Y, por supuesto, que el control de mercados permita capitalizar la inversi\u00f3n realizada para cumplirla.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00abEn Espa\u00f1a somos l\u00edderes internacionales en sostenibilidad\u00bb<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>\u2013 Vamos por partes. \u00bfQu\u00e9 quieres decir con coherencia legislativa?<\/p>\n<p>El Reglamento Europeo de Dise\u00f1o Ecol\u00f3gico marca una serie de requisitos que deber\u00e1n cumplir los nuevos productos, tambi\u00e9n los textiles, como incorporar un porcentaje de materias recicladas o ciertos criterios de ecodise\u00f1o que pasan por prendas monomaterial, etc. Pero la sostenibilidad de un producto textil es mucho m\u00e1s compleja y depende de la categor\u00eda de producto y del uso que se le vaya a dar.<\/p>\n<p><strong>\u2013 \u00bfUn ejemplo que podamos entender?<\/strong><\/p>\n<p>La ropa t\u00e9cnica laboral o incluso la deportiva son ejemplos muy ilustrativos. Para que sea ropa duradera y cumpla los requisitos t\u00e9cnicos por los que ha sido ideada, a menudo debe de renunciar al monomaterial y a las materias primas recicladas. Dos pr\u00e1cticas vistas como poco circulares pero que en realidad incrementar\u00e1n su durabilidad y su eficiencia. Si dicotom\u00edas como \u00e9stas no se explican bien, la propia legislaci\u00f3n puede convertirse en una herramienta de greenwashing.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00abLa propia legislaci\u00f3n puede convertirse en una herramienta de greenwashing\u00bb.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong>\u2013 \u00bfY c\u00f3mo puede ser la legislaci\u00f3n m\u00e1s coherente?<\/strong><\/p>\n<p>Se deber\u00e1, que de hecho ya se est\u00e1 haciendo, estudiar el sector textil con mucho detalle y tener en cuenta toda su casu\u00edstica. Habr\u00eda que analizar cada categor\u00eda de producto por separado y cada material. Y marcar unos requisitos distintos para cada uno de ellos.<\/p>\n<p>Pero no solo se trata de legislaci\u00f3n, sino de educaci\u00f3n ciudadana.<\/p>\n<p>Retomando el ejemplo anterior. Mucha ropa ideada para practicar deporte est\u00e1 siendo usada para el d\u00eda a d\u00eda y sometida a muchos m\u00e1s lavados de lo que estaba pensado. Todo ello genera el desgaste inadecuado de un material que ha implicado muchos recursos naturales. Y en algunos casos, adem\u00e1s, supone el desprendimiento de muchos micropl\u00e1sticos. La prenda hab\u00eda sido confeccionada para la sostenibilidad, pero su uso no es adecuado.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00abNo solo se trata de legislaci\u00f3n, sino de educaci\u00f3n ciudadana\u00bb.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong>\u2013 Tenemos poca cultura textil.<\/strong><\/p>\n<p>Muy poca. Y es una l\u00e1stima, sobre todo porque muchas regiones de Espa\u00f1a est\u00e1n muy ligadas al textil, pero la cultura en esta \u00e1rea se ha perdido. Es muy poca la gente que conoce los procesos que se esconden detr\u00e1s de una simple camiseta, y ello dificulta mucho tanto la compra de ropa como su posterior cuidado en casa. Cerca de los industriales textiles hay m\u00e1s conocimiento de c\u00f3mo se hace un hilo, c\u00f3mo se teje y c\u00f3mo se tinta, con ese conocimiento es m\u00e1s f\u00e1cil entender la sostenibilidad sectorial.<\/p>\n<p><strong>\u2013 \u00bfC\u00f3mo se puede ayudar al consumidor a hacerlo mejor?<\/strong><\/p>\n<p>Educando desde la escuela, por ejemplo. De hecho, una de las labores de Texfor es la formaci\u00f3n y la divulgaci\u00f3n, en escuelas, con cursos especializados y con la atenci\u00f3n a medios de comunicaci\u00f3n. Un proyecto muy interesante fue Erasmus + Ecotex, desde el que se formaron m\u00e1s de 5.550 personas.<\/p>\n<p><strong>\u2013 Y la propia industria, \u00bfpuede de alguna manera influir en el comportamiento del usuario final?<\/strong><\/p>\n<p>En realidad ya lo hace, dando ejemplo, que a veces no es lo m\u00e1s medi\u00e1tico pero s\u00ed lo m\u00e1s efectivo. La obsesi\u00f3n de los industriales espa\u00f1oles es ofrecer la m\u00e1xima calidad y durabilidad con la mayor eficiencia energ\u00e9tica, de agua, de qu\u00edmica, etc. Por principios, por reputaci\u00f3n, por legislaci\u00f3n y por competitividad econ\u00f3mica.<\/p>\n<p>Otra cosa es formar al usuario en el uso de la prenda. Eso ya es m\u00e1s complicado, puesto que la industria no est\u00e1 en contacto directo con la ciudadan\u00eda, y los escasos recursos que invierten en comunicaci\u00f3n se destinan a relacionarse con las marcas, que son sus clientes directos. Supongo que deber\u00e1n ser las marcas quienes fomenten estas buenas pr\u00e1cticas a trav\u00e9s de sus comunicaciones con el consumidor.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00abDeber\u00e1n ser las marcas quienes fomenten estas buenas pr\u00e1cticas a trav\u00e9s de sus comunicaciones con el consumidor\u00bb.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong>\u2013 \u00bfEl Pasaporte Digital de Producto puede ser una buena herramienta?<\/strong><\/p>\n<p>Naturalmente que ayudar\u00e1 mucho, sobre todo a que las personas consumidoras con cierto inter\u00e9s accedan f\u00e1cilmente a informaci\u00f3n muy \u00fatil. El reto es llegar a las que no muestran tanto inter\u00e9s.<\/p>\n<p><strong>\u2013 Francia ha anunciado el lanzamiento de \u201cecoscore\u201d, una etiqueta que persigue simplificar estos mensajes.<\/strong><\/p>\n<p>S\u00ed, se trata de un sem\u00e1foro parecido al de la certificaci\u00f3n energ\u00e9tica que identifica visualmente la huella ambiental del producto textil. Es muy interesante y toda ayuda ser\u00e1 bienvenida, pero siempre sin olvidar que la sostenibilidad y la circularidad de una prenda no se limitan a la huella ambiental. El uso que se haga en casa y el fin de vida que se les de, son claves.<\/p>\n<p>En los mercados del sur de Europa el sem\u00e1foro, todav\u00eda, es el precio, aunque creo que hay una tendencia clara hacia el \u201cmenos es m\u00e1s\u201d.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00abLa sostenibilidad y la circularidad de una prenda no se limitan a la huella ambiental. El uso que se haga en casa y el fin de vida que se les de, son claves\u00bb.<\/p><\/blockquote>\n<p><strong>\u2013 Al principio de la entrevista apuntabas que otro de los grandes retos de la transici\u00f3n legislativa hacia la circularidad es el control de mercados y el ser competitivos en ellos. \u00bfQu\u00e9 significa?<\/strong><\/p>\n<p>La legislaci\u00f3n europea aplica a todos los productos que se quieran comercializar dentro de Europa.Y aqu\u00ed lo complicado ser\u00e1 controlar aquellas producciones que vienen de fuera. Actualmente el control de aduanas es complejo de gestionar, lo deja patente el proyecto REACH 4 textiles (*).<\/p>\n<p>El miedo del sector industrial espa\u00f1ol y europeo es la divergencia entre lo que se legisla y lo que se puede controlar, y el dumping ambiental y social, ya que se est\u00e1n realizando fuertes inversiones para adaptarse a la normativa e incrementar todav\u00eda m\u00e1s esta circularidad y la dificultad es que el mercado valore esta excelencia.<\/p>\n<p>Estamos en una situaci\u00f3n muy compleja en Europa de falta de competitividad por esa falta de reconocimiento de variables ambientales (descarbonizaci\u00f3n, eficiencia en agua y manejo y gesti\u00f3n de qu\u00edmicos, evitar qu\u00edmica peligrosa, etc.). Todo ello son recursos, y ni siquiera las administraciones p\u00fablicas que legislan aplican la coherencia de sus normas para las compras.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00abEl miedo del sector industrial espa\u00f1ol y europeo es la divergencia entre lo que se legisla y lo que se puede controlar\u00bb.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong>\u2013 En este sentido, \u00bfqu\u00e9 estrategias est\u00e1n implementando los industriales espa\u00f1oles para minimizar la generaci\u00f3n de residuos y promover el reciclaje en toda la cadena de suministro?<\/strong><\/p>\n<p>Como te comentaba, es algo que se viene haciendo desde siempre, como las hilaturas que solo trabajan con hilos regenerados, que no solo aprovechan la materia prima si no tambi\u00e9n el tintado original. Tambi\u00e9n hay quienes ya han empezado a trabajar con colorantes biobasados que sustituyen a la qu\u00edmica m\u00e1s convencional. Y, obviamente, muchas f\u00e1bricas est\u00e1n avanzando muy r\u00e1pidamente hacia la descarbonizaci\u00f3n, a trav\u00e9s de placas fotovoltaicas y reaprovechamiento pr\u00e1cticamente al 100% del agua y mejorar la gesti\u00f3n de los residuos s\u00f3lidos a trav\u00e9s de simbiosis industrial.<\/p>\n<p>Recientemente en Texfor hemos impartido una formaci\u00f3n espec\u00edfica sobre reciclado textil, analizando casos de \u00e9xito y las tecnolog\u00edas m\u00e1s punteras que se est\u00e1n usando en la actualidad y las posibilidades de innovaci\u00f3n a corto y medio plazo y tenemos actividades en temas de descarbonizaci\u00f3n, qu\u00edmica, etc.<\/p>\n<p><strong>\u2013 \u00bfY est\u00e1 la industria apostando tambi\u00e9n por nuevos modelos de negocio basados en la circularidad?<\/strong><\/p>\n<p>Lo llevan en el ADN por competitividad. Ahora mismo est\u00e1n inmersos en la digitalizaci\u00f3n y en ser punteros en industria 4.0 y adem\u00e1s colaborando entre ellos y con alianzas muy interesantes con startups creadas por este fin, como Recovo, que da salida a tejidos que han quedado descatalogados, o con empresas como Circoolar o Deleite Wear, que fomentan la servitizaci\u00f3n del textil o empresas que buscan simbiosis industrial, nuevas aplicaciones para el residuo, como el caso de Insertega o incluso Moda-Re.<\/p>\n<p>(*) REACH 4 textiles es un programa de Euratex que promueve una vigilancia del mercado de productos textiles justa y efectiva con el objetivo de, entre otros, mantener los productos que no cumplen con las normas fuera del mercado \u00fanico europeo.<\/p>\n<p>Este art\u00edculo forma parte de un espacio de debate impulsado por Girbau LAB y So Good So Cute que persigue generar reflexi\u00f3n y aportar luz a aspectos esenciales de la circularidad en la industria textil. <a href=\"https:\/\/labs.100x100.net\/projects\/girbaulab\/es\/cultura\/conversaciones-sobre-circularidad-textil\/\" target=\"_blank\" rel=\"noopener\">Ver otros art\u00edculos publicados.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Texfor es la Confederaci\u00f3n de la Industria Textil, la entidad espa\u00f1ola con mayor representatividad del sector textil. Actualmente agrupa a m\u00e1s de 4.000 empresas, la gran mayor\u00eda pymes, que dan empleo a m\u00e1s de 45.000 trabajadores y generan una riqueza anual superior a los 5.000 M\u20ac. Una organizaci\u00f3n clave para acelerar la circularidad de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"class_list":["post-3103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00abNuestra industria es l\u00edder en sostenibilidad, pero como ciudadanos tenemos muy poca cultura textil\u00bb - Girbau LAB<\/title>\n<meta name=\"description\" content=\"Entrevistamos a David Allo, responsable de sostenibilidad de Texfor, la Confederaci\u00f3n de la Industria Textil espa\u00f1ola\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abNuestra industria es l\u00edder en sostenibilidad, pero como ciudadanos tenemos muy poca cultura textil\u00bb - Girbau LAB\" \/>\n<meta property=\"og:description\" content=\"Entrevistamos a David Allo, responsable de sostenibilidad de Texfor, la Confederaci\u00f3n de la Industria Textil espa\u00f1ola\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/\" \/>\n<meta property=\"og:site_name\" content=\"Girbau LAB\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-27T12:53:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-18T10:34:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2025\/03\/david-allo-3-sgsc-girbau-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"girbau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@girbaulab\" \/>\n<meta name=\"twitter:site\" content=\"@girbaulab\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"girbau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/\"},\"author\":{\"name\":\"girbau\",\"@id\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/#\\\/schema\\\/person\\\/23b9b3863288ce7c33d38f38f3a3af5f\"},\"headline\":\"\u00abNuestra industria es l\u00edder en sostenibilidad, pero como ciudadanos tenemos muy poca cultura textil\u00bb\",\"datePublished\":\"2024-04-27T12:53:31+00:00\",\"dateModified\":\"2025-03-18T10:34:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/\"},\"wordCount\":1675,\"publisher\":{\"@id\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hundreds-wordpress-uploads.s3.amazonaws.com\\\/girbaulab\\\/uploads\\\/2025\\\/03\\\/david-allo-3-sgsc-girbau-1-1.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/\",\"url\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/\",\"name\":\"\u00abNuestra industria es l\u00edder en sostenibilidad, pero como ciudadanos tenemos muy poca cultura textil\u00bb - Girbau LAB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hundreds-wordpress-uploads.s3.amazonaws.com\\\/girbaulab\\\/uploads\\\/2025\\\/03\\\/david-allo-3-sgsc-girbau-1-1.jpg\",\"datePublished\":\"2024-04-27T12:53:31+00:00\",\"dateModified\":\"2025-03-18T10:34:50+00:00\",\"description\":\"Entrevistamos a David Allo, responsable de sostenibilidad de Texfor, la Confederaci\u00f3n de la Industria Textil espa\u00f1ola\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hundreds-wordpress-uploads.s3.amazonaws.com\\\/girbaulab\\\/uploads\\\/2025\\\/03\\\/david-allo-3-sgsc-girbau-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/hundreds-wordpress-uploads.s3.amazonaws.com\\\/girbaulab\\\/uploads\\\/2025\\\/03\\\/david-allo-3-sgsc-girbau-1-1.jpg\",\"width\":800,\"height\":533,\"caption\":\"We interview David Allo, Head of Sustainability at Texfor, the Confederation of the Spanish Textile Industry.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/david-allo-texfor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abNuestra industria es l\u00edder en sostenibilidad, pero como ciudadanos tenemos muy poca cultura textil\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/\",\"name\":\"Girbau LAB\",\"description\":\"Girbau LAB is a space for collaboration created to add value to the laundry industry through innovation\",\"publisher\":{\"@id\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/#organization\",\"name\":\"Girbau LAB\",\"url\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hundreds-wordpress-uploads.s3.amazonaws.com\\\/girbaulab\\\/uploads\\\/2022\\\/10\\\/Girbau_LAB_logo.png\",\"contentUrl\":\"https:\\\/\\\/hundreds-wordpress-uploads.s3.amazonaws.com\\\/girbaulab\\\/uploads\\\/2022\\\/10\\\/Girbau_LAB_logo.png\",\"width\":562,\"height\":90,\"caption\":\"Girbau LAB\"},\"image\":{\"@id\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/girbaulab\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/girbaulab\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/girbaulab.com\\\/es\\\/#\\\/schema\\\/person\\\/23b9b3863288ce7c33d38f38f3a3af5f\",\"name\":\"girbau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g\",\"caption\":\"girbau\"},\"sameAs\":[\"https:\\\/\\\/labs.100x100.net\\\/projects\\\/girbaulab\\\/private\"],\"url\":\"http:\\\/\\\/www.girbaulab.com\\\/es\\\/author\\\/girbau\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abNuestra industria es l\u00edder en sostenibilidad, pero como ciudadanos tenemos muy poca cultura textil\u00bb - Girbau LAB","description":"Entrevistamos a David Allo, responsable de sostenibilidad de Texfor, la Confederaci\u00f3n de la Industria Textil espa\u00f1ola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/","og_locale":"es_ES","og_type":"article","og_title":"\u00abNuestra industria es l\u00edder en sostenibilidad, pero como ciudadanos tenemos muy poca cultura textil\u00bb - Girbau LAB","og_description":"Entrevistamos a David Allo, responsable de sostenibilidad de Texfor, la Confederaci\u00f3n de la Industria Textil espa\u00f1ola","og_url":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/","og_site_name":"Girbau LAB","article_published_time":"2024-04-27T12:53:31+00:00","article_modified_time":"2025-03-18T10:34:50+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2025\/03\/david-allo-3-sgsc-girbau-1-1.jpg","type":"image\/jpeg"}],"author":"girbau","twitter_card":"summary_large_image","twitter_creator":"@girbaulab","twitter_site":"@girbaulab","twitter_misc":{"Escrito por":"girbau","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/#article","isPartOf":{"@id":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/"},"author":{"name":"girbau","@id":"https:\/\/girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f"},"headline":"\u00abNuestra industria es l\u00edder en sostenibilidad, pero como ciudadanos tenemos muy poca cultura textil\u00bb","datePublished":"2024-04-27T12:53:31+00:00","dateModified":"2025-03-18T10:34:50+00:00","mainEntityOfPage":{"@id":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/"},"wordCount":1675,"publisher":{"@id":"https:\/\/girbaulab.com\/es\/#organization"},"image":{"@id":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2025\/03\/david-allo-3-sgsc-girbau-1-1.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/","url":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/","name":"\u00abNuestra industria es l\u00edder en sostenibilidad, pero como ciudadanos tenemos muy poca cultura textil\u00bb - Girbau LAB","isPartOf":{"@id":"https:\/\/girbaulab.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/#primaryimage"},"image":{"@id":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/#primaryimage"},"thumbnailUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2025\/03\/david-allo-3-sgsc-girbau-1-1.jpg","datePublished":"2024-04-27T12:53:31+00:00","dateModified":"2025-03-18T10:34:50+00:00","description":"Entrevistamos a David Allo, responsable de sostenibilidad de Texfor, la Confederaci\u00f3n de la Industria Textil espa\u00f1ola","breadcrumb":{"@id":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/#primaryimage","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2025\/03\/david-allo-3-sgsc-girbau-1-1.jpg","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2025\/03\/david-allo-3-sgsc-girbau-1-1.jpg","width":800,"height":533,"caption":"We interview David Allo, Head of Sustainability at Texfor, the Confederation of the Spanish Textile Industry."},{"@type":"BreadcrumbList","@id":"http:\/\/www.girbaulab.com\/es\/david-allo-texfor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/girbaulab.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abNuestra industria es l\u00edder en sostenibilidad, pero como ciudadanos tenemos muy poca cultura textil\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/girbaulab.com\/es\/#website","url":"https:\/\/girbaulab.com\/es\/","name":"Girbau LAB","description":"Girbau LAB is a space for collaboration created to add value to the laundry industry through innovation","publisher":{"@id":"https:\/\/girbaulab.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/girbaulab.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/girbaulab.com\/es\/#organization","name":"Girbau LAB","url":"https:\/\/girbaulab.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/girbaulab.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png","contentUrl":"https:\/\/hundreds-wordpress-uploads.s3.amazonaws.com\/girbaulab\/uploads\/2022\/10\/Girbau_LAB_logo.png","width":562,"height":90,"caption":"Girbau LAB"},"image":{"@id":"https:\/\/girbaulab.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/girbaulab","https:\/\/www.linkedin.com\/company\/girbaulab\/"]},{"@type":"Person","@id":"https:\/\/girbaulab.com\/es\/#\/schema\/person\/23b9b3863288ce7c33d38f38f3a3af5f","name":"girbau","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe57a3f139ea81c65a338e37a8064b4e80844f839737532820c9107eb9e1966f?s=96&d=mm&r=g","caption":"girbau"},"sameAs":["https:\/\/labs.100x100.net\/projects\/girbaulab\/private"],"url":"http:\/\/www.girbaulab.com\/es\/author\/girbau\/"}]}},"_links":{"self":[{"href":"http:\/\/www.girbaulab.com\/es\/wp-json\/wp\/v2\/posts\/3103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.girbaulab.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.girbaulab.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.girbaulab.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.girbaulab.com\/es\/wp-json\/wp\/v2\/comments?post=3103"}],"version-history":[{"count":1,"href":"http:\/\/www.girbaulab.com\/es\/wp-json\/wp\/v2\/posts\/3103\/revisions"}],"predecessor-version":[{"id":3104,"href":"http:\/\/www.girbaulab.com\/es\/wp-json\/wp\/v2\/posts\/3103\/revisions\/3104"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.girbaulab.com\/es\/wp-json\/wp\/v2\/media\/3099"}],"wp:attachment":[{"href":"http:\/\/www.girbaulab.com\/es\/wp-json\/wp\/v2\/media?parent=3103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.girbaulab.com\/es\/wp-json\/wp\/v2\/categories?post=3103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}